{"id":8758,"count":2,"description":"","link":"https:\/\/www.sceltedigusto.it\/public\/tag\/amira-palermo\/","name":"Amira Palermo","slug":"amira-palermo","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags\/8758"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts?tags=8758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}