{"id":8180,"count":1,"description":"","link":"https:\/\/www.sceltedigusto.it\/public\/tag\/francesca-marsetti\/","name":"Francesca Marsetti","slug":"francesca-marsetti","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags\/8180"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts?tags=8180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}