{"id":7583,"count":1,"description":"","link":"https:\/\/www.sceltedigusto.it\/public\/tag\/verdicchio-dei-castelli-di-jesi-classico-superiore-doc\/","name":"Verdicchio dei Castelli di Jesi Classico Superiore DOC","slug":"verdicchio-dei-castelli-di-jesi-classico-superiore-doc","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags\/7583"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts?tags=7583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}