{"id":6582,"count":1,"description":"","link":"https:\/\/www.sceltedigusto.it\/public\/tag\/giornata-mondiale-dellalimentazione\/","name":"Giornata Mondiale dell'Alimentazione","slug":"giornata-mondiale-dellalimentazione","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags\/6582"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts?tags=6582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}