{"id":1819,"count":1,"description":"","link":"https:\/\/www.sceltedigusto.it\/public\/tag\/chiesa\/","name":"Chiesa","slug":"chiesa","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags\/1819"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts?tags=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}