{"id":9407,"date":"2015-04-27T20:11:29","date_gmt":"2015-04-27T18:11:29","guid":{"rendered":"http:\/\/www.sceltedigusto.it\/public\/?p=9407"},"modified":"2015-04-27T20:11:29","modified_gmt":"2015-04-27T18:11:29","slug":"gualtiero-marchesi-il-passato-e-pieno-di-novita","status":"publish","type":"post","link":"https:\/\/www.sceltedigusto.it\/public\/gualtiero-marchesi-il-passato-e-pieno-di-novita\/","title":{"rendered":"Gualtiero Marchesi: &#8221; Il passato \u00e8 pieno di novit\u00e0&#8221;"},"content":{"rendered":"<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/10\/gualtiero-marchesi.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-8088 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/10\/gualtiero-marchesi-300x225.jpg\" alt=\"gualtiero-marchesi\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/10\/gualtiero-marchesi-300x225.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/10\/gualtiero-marchesi.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Riceviamo e volentieri pubblichiamo:<\/p>\n<p>&#8220;<em>C\u2019\u00e8 un libro degli anni Settanta, credo ancora letto, che si intitola\u00a0 &#8220;Lo zen e l\u2019arte della manutenzione della motocicletta.&#8221; Un bel titolo che cito volentieri per questa summa di ricette che rappresenta il nostro passato culinario.<\/em><br \/>\n<em> Lo zen riguarda la parte vuota del bicchiere, il contenuto da riempiere non il contenitore. Il contenuto che comprende la storia, la tradizione, i microclimi, i prodotti, il gusto, \u00e8 pieno di novit\u00e0, \u00e8 ricchissimo di suggerimenti e va, pertanto, curato con la massima attenzione. Col tempo, per me la cucina \u00e8 diventata un\u2019arte e ha significato la libert\u00e0 di viaggiare in moto,di fare manutenzione, aggiornando, tappa dopo tappa, il sapore stesso della vita. In questo libro, pubblicato da De <a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/01\/gualtiero_marchesi_alma-1.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-6006 alignright\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/01\/gualtiero_marchesi_alma-1-300x168.jpg\" alt=\"gualtiero_marchesi_alma-1\" width=\"300\" height=\"168\" \/><\/a>Agostini, ho fatto il punto sul patrimonio della cucina italiana, osservando con amore quello che \u00e8 stato fatto, proponendo una versione aggiornata dei piatti, senza doverli stravolgere per sembrare originale. Rispetto a certe bufale creative, a certi esercizi di stile, all\u2019agonismo televisivo fine a se stesso,studiare e confrontarsi \u00e8 la scelta migliore.<\/em><br \/>\n<em> Nel grande ricettario tradizionale si avverte l\u2019impronta del mondo femminile, il sapere di generazioni di madri, l\u2019attaccamento alla terra, cos\u00ec attuale in tempi di Expo; c\u2019\u00e8 soprattutto quello che predico da anni: il bello puro \u00e8 il vero buono, come dice mia figlia Paola. Se ognuno di noi, responsabile della salute altrui, mettesse la bellezza e la verit\u00e0 al centro del proprio lavoro, lavorerebbe meglio e con pi\u00f9 gioia. Contemplare un bel paesaggio fa bene all\u2019anima.<\/em><br \/>\n<em> Parliamoci chiaro, la cucina \u00e8 prima di tutto un impegno, ma anche un modo di esprimersi, un linguaggio, in cui la personalit\u00e0 non pu\u00f2 superare la competenza, n\u00e9 la competenza escludere il talento. Solo chi \u00e8 responsabile \u00e8 veramente libero e chi \u00e8 libero aggiunge un po\u2019 di bellezza e di verit\u00e0 a questo mondo. Dopo questa nuova fatica editoriale, che tocca il passato e il presente della cucina italiana, il prossimo appuntamento sar\u00e0 con un libro di piatti firmati.<\/em><br \/>\n<em> Piatti in cui ho cercato di lasciare un segno, in nome della forma e della mater<\/em>ia.&#8221;<\/p>\n<p><strong>Gualtiero Marchesi<\/strong><\/p>\n<p>Il volume\u00a0 &#8220;Gualtiero Marchesi &#8211; LA CUCINA ITALIANA-\u00a0 Il Grande Ricettario&#8221; sar\u00e0 in libreria da domani\u00a0 28 aprile<\/p>\n<p>Le oltre 1.500 preparazioni di questo ricettario sono quelle della classica cucina italiana, interpretate nella \u201cfilosofia\u201d di Gualtiero Marchesi. Sono ricette familiari e regionali, rivisitate con gli occhi di un cuoco d\u2019eccellenza che sa valorizzare i piatti de<em><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2015\/04\/marchesi.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-9408 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2015\/04\/marchesi-227x300.jpg\" alt=\"marchesi\" width=\"227\" height=\"300\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2015\/04\/marchesi-227x300.jpg 227w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2015\/04\/marchesi.jpg 314w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/><\/a><\/em>lla tradizione e interpretare le nuove tendenze con tecniche e segreti dell\u2019alta cucina. La suddivisione delle preparazioni \u00e8 fatta sulla base della provenienza territoriale, sotto il nome di \u201cricette di costa\u201d e \u201cricette dell\u2019entroterra\u201d.<\/p>\n<p>Ma l\u2019esperienza di Marchesi e la sua capacit\u00e0 di leggere le trasformazioni degli stili di vita hanno portato a rivedere molti piatti, i cui nomi sono dei \u201cclassici\u201d nella nostra tradizione culinaria,adattandole in base alle esigenze moderne,ormai mutate rispetto a quello degli anni del Dopoguerra: l\u2019uso delle materie prime \u00e8 attualizzato ed \u00e8 reso pi\u00f9 consono ai nostri giorni, permettendo realizzazioni pi\u00f9 leggere ma altrettanto gustose. Dall\u2019antipasto al dolce, un percorso nelle vie del gusto ricco di proposte e di idee. Dalle preparazioni pi\u00f9 classiche a quelle pi\u00f9 ricercate,<br \/>\nun vademecum completo per cuochi appassionati, ma anche un aiuto prezioso per chi muovei primi passi in cucina seguendo gli insegnamenti di un grande Maestro.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e volentieri pubblichiamo: &#8220;C\u2019\u00e8 un libro degli anni Settanta, credo ancora letto, che si intitola\u00a0 &#8220;Lo zen e l\u2019arte della manutenzione della motocicletta.&#8221; Un bel titolo che cito volentieri per questa summa di ricette che rappresenta il nostro passato culinario. Lo zen riguarda la parte vuota del bicchiere, il contenuto da riempiere non il [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":6006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5435,5],"tags":[821],"jetpack_featured_media_url":"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/01\/gualtiero_marchesi_alma-1.jpg","_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/9407"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/comments?post=9407"}],"version-history":[{"count":1,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/9407\/revisions"}],"predecessor-version":[{"id":9409,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/9407\/revisions\/9409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media\/6006"}],"wp:attachment":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media?parent=9407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/categories?post=9407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags?post=9407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}