{"id":2932,"date":"2012-02-14T06:37:21","date_gmt":"2012-02-14T05:37:21","guid":{"rendered":"http:\/\/www.sceltedigusto.it\/public\/Test\/a-rimini-sapore-tasting-experience\/"},"modified":"2013-11-16T21:11:25","modified_gmt":"2013-11-16T20:11:25","slug":"a-rimini-sapore-tasting-experience","status":"publish","type":"post","link":"https:\/\/www.sceltedigusto.it\/public\/a-rimini-sapore-tasting-experience\/","title":{"rendered":"A Rimini, Sapore Tasting Experience"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\" size-full wp-image-2549\" src=\"http:\/\/www.sceltedigusto.it\/public\/Test\/wp-content\/uploads\/2011\/12\/pasta.jpg\" border=\"0\" width=\"300\" width=\"548\" height=\"674\" \/>Gusti, riti e tendenze nell\u2019alimentazione extradomestica. Tutto questo \u00e8 il tema di \u201cSapore tasting experience\u201d, evento ai nastri di partenza a Rimini a fine mese come appuntamento di riferimento per il settore professionale del food &amp; beverage fuori casa patrocinato da Ministero delle Politiche Agricole, Regione Emilia Romagna, Provincia di Rimini e Cna Alimentare con il supporto dell\u2019associazione Professionale Cuochi Italiani (P.Pi.)<strong> <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p><strong> <\/strong><\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\" alignleft size-full wp-image-2930\" src=\"http:\/\/www.sceltedigusto.it\/public\/Test\/wp-content\/uploads\/2012\/02\/logo_sapore.jpg\" border=\"0\" width=\"250\" style=\"margin: 5px; float: left;\" width=\"1907\" height=\"1128\" \/>Numerosi i professionisti che si troveranno per dare vita a uno chef contest di alto livello, sublimato anche dalla prima edizione del Concorso Sapore Grand Prix coordinato dallo chef Roberto Carcangiu per tre categorie: students (studenti degli istituti alberghieri), juniores (chef diplomati fino ai 25 anni compresi) e professionals (over 26). Sono attesi concorrenti anche dalla Korea e dalla Polonia. La sfida sar\u00e0 sulla cucina internazionale calda e fredda con prevalenza di prodotti industriali, surgelati e no. La giuria sar\u00e0 composta da giornalisti, chef, esperti del settore. Momenti formativi e dimostrativi live arricchiranno l\u2019evento con gli \u201cShow cooking reed gourmet\u201d (tra gli argomenti trattati per esempio il dolce nella ristorazione, la cottura a bassa temperatura e la pasta fresca nell\u2019alta ristorazione) attualit\u00e0 o dibattiti sul fare business in uno dei settori che muove sempre pi\u00f9 numeri importanti con precise tendenze da parte del consumatore. Si calcola infatti che la spesa per i consumi fuori casa sia oggi pari a 468 miliardi di euro, incrementati nell\u2019ultimo decennio di 21 miliardi.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\" alignright size-full wp-image-2931\" src=\"http:\/\/www.sceltedigusto.it\/public\/Test\/wp-content\/uploads\/2012\/02\/mia 1.jpg\" border=\"0\" width=\"250\" style=\"margin: 5px; float: right;\" width=\"4000\" height=\"3000\" \/>In Italia la crescita della domanda alimentare \u00e8 da attribuirsi per la quasi totalit\u00e0 al fuori casa. Un panorama a tutto tondo, dalle attrezzature al personale al marketing fino ai prodotti, occasioni di formazione e business che proporr\u00e0 sezioni dedicate alle birre speciali artigianali italiane ed estere (premio alla birra dell\u2019anno) e al beverage per il canale horeca, al catering, alla filiera ittica, agli alimenti surgelati, alla pasta, al bio, al gluten free, alle specialit\u00e0 regionali, alla pizza, all\u2019olio e il vino. A questo proposito, \u00e8 stato pensato il premio \u201cInnovation award\u201d, in apertura di salone, per evidenziare le novit\u00e0 pronte ad invadere il mercato per soddisfare una domanda sempre mutevole, attenta alle tendenze. Molte le presenze straniere, da tutti i continenti. Contemporaneamente, si svolger\u00e0 \u201cCooking pasta\u201d, il campionato italiano della ristorazione con idee dall\u2019antipasto al dolce che metter\u00e0 in competizione giovani pastai affiancati da maestri e giovani Chef o guru stellati su proposte innovative dalle diverse regioni d\u2019Italia su produzioni secche e fresche, all\u2019uovo, aromatizzate e ripiene. Il concorso \u00e8 organizzato in collaborazione con la European Chefs Academy e con Raimondo Mendolia, chef stellato della Cast Alimenti specializzato nella pasta. Il settore pasta \u00e8 sotto stretta osservazione: sono attesi buyer da Russia, Ucraina ed ex Repubbliche sovietiche, Polonia, Repubblica Ceca, Slovacchia, Francia, Germania, Spagna, Gran Bretagna, Benelux, Egitto, Emirati Arabi, Turchia, Sud Est asiatico ed Estremo Oriente per apprezzare il lavoro di grossisti, produttori, ristoratori e importatori. Segno che il tricolore ancora \u00e8 simbolo di qualit\u00e0 e stile nel culto del mangiar bene e della ristorazione. Via anche al 13mo \u201cConcorso mondiale della Nazionale pizzaioli\u201d organizzato dalla Nip e dedicato alla pizza con prodotti bio, senza glutine e con farine alternative. Una visione sul futuro del gusto come recita lo slogan.<\/p>\n<p style=\"text-align: justify;\"><strong>Paola Piovesana<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gusti, riti e tendenze nell\u2019alimentazione extradomestica. Tutto questo \u00e8 il tema di \u201cSapore tasting experience\u201d, evento ai nastri di partenza a Rimini a fine mese come appuntamento di riferimento per il settore professionale del food &amp; beverage fuori casa patrocinato da Ministero delle Politiche Agricole, Regione Emilia Romagna, Provincia di Rimini e Cna Alimentare con [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":2549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[29],"tags":[4137,4136,4138,3468,4139,4135,4134],"jetpack_featured_media_url":"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2011\/12\/pasta.jpg","_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/2932"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/comments?post=2932"}],"version-history":[{"count":1,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/2932\/revisions"}],"predecessor-version":[{"id":4321,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/2932\/revisions\/4321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media\/2549"}],"wp:attachment":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media?parent=2932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/categories?post=2932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags?post=2932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}