{"id":15664,"date":"2018-06-07T16:14:10","date_gmt":"2018-06-07T14:14:10","guid":{"rendered":"http:\/\/www.sceltedigusto.it\/public\/?p=15664"},"modified":"2018-06-07T16:14:10","modified_gmt":"2018-06-07T14:14:10","slug":"made-in-italy-meta-dei-cinesi-non-conosce-i-prodotti-italiani-e-per-loro-il-vino-e-sinonimo-di-francia","status":"publish","type":"post","link":"https:\/\/www.sceltedigusto.it\/public\/made-in-italy-meta-dei-cinesi-non-conosce-i-prodotti-italiani-e-per-loro-il-vino-e-sinonimo-di-francia\/","title":{"rendered":"Made in Italy. Met\u00e0 dei Cinesi non conosce i prodotti italiani. E per loro il vino \u00e8 sinonimo di Francia"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2012\/02\/cinesevino.jpg\"><img loading=\"lazy\" class=\"alignnone wp-image-2967\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2012\/02\/cinesevino.jpg\" alt=\"cinesevino\" width=\"830\" height=\"1173\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2012\/02\/cinesevino.jpg 354w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2012\/02\/cinesevino-212x300.jpg 212w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2012\/02\/cinesevino-150x212.jpg 150w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2012\/02\/cinesevino-300x424.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2012\/02\/cinesevino-297x420.jpg 297w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/a>La pasta e il Barolo<\/strong> sarebbero il cibo e il vino italiani pi\u00f9 conosciuti dall\u2019upper class cinese. Ma a vincere \u00e8 la non conoscenza del made in Italy, con la met\u00e0 dei consumatori chiamati ad associare al Belpaese un prodotto\/brand agroalimentare che risponde \u2018non so\u2019. Lo rivela un estratto dell\u2019indagine dell\u2019Osservatorio Paesi terzi di Business Strategies sul posizionamento del made in Italy in Cina, condotta da<strong> Nomisma Wine Monitor<\/strong> su un campione di 1.000 cittadini dal reddito medio-alto residenti a <strong>Pechino e Shanghai<\/strong>.<\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1.jpg\"><img loading=\"lazy\" class=\"alignnone wp-image-14758 \" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1.jpg\" alt=\"quadrifoglio pasta1\" width=\"842\" height=\"631\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1.jpg 770w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1-300x225.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1-768x576.jpg 768w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1-150x112.jpg 150w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1-696x522.jpg 696w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1-560x420.jpg 560w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1-80x60.jpg 80w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1-265x198.jpg 265w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><\/a>\u201c<em>L\u2019equazione Italia-buona tavola \u00e8 un\u2019associazione che non pu\u00f2 ancora essere data per scontata in Cina<\/em> \u2013 ha detto Silvana Ballotta, Ceo di Business Strategies \u2013.<em> A fronte di un mercato in crescita e di un primo trimestre record a + 41,4% per il vino italiano, solo la met\u00e0 dei consumatori dimostra di saper associare al nostro Paese almeno un prodotto enogastronomico. Questa mancanza, da un lato di conoscenza e dall\u2019altro di promozione, si traduce in un deficit di comprensione sul fronte consumer e in una conseguente difficolt\u00e0 di posizionamento per i nostri produttori, a vantaggio dei competitor\u201d. Quasi 7 cinesi su 10, infatti, associano la categoria \u201cvino\u201d alla Francia, mentre sono solo 2 su 10 quelli che si orientano verso l\u2019Italia. Un risultato che migliora solo leggermente quando si parla di cibo, con il Belpaese menzionato da un quarto del campione, dietro al Giappone (37%), ma prima di Francia (15%) e Usa (14%).&#8221;<\/em><\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/04\/mondo-vino_0.jpg\"><img loading=\"lazy\" class=\"alignnone wp-image-6811 \" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/04\/mondo-vino_0.jpg\" alt=\"mondo vino_0\" width=\"831\" height=\"687\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/04\/mondo-vino_0.jpg 474w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/04\/mondo-vino_0-300x248.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2014\/04\/mondo-vino_0-150x124.jpg 150w\" sizes=\"(max-width: 831px) 100vw, 831px\" \/><\/a>Secondo la survey condotta nelle due metropoli asiatiche, \u00e8 la pasta la pi\u00f9 conosciuta dai cinesi, nominata dal 31% di coloro che danno un\u2019indicazione di prodotto e seguita dai brand Ferrero (10%) e Illy (4%). E mentre restano appena fuori dal podio la pizza (4%) e l\u2019olio d\u2019oliva (3%), a sorpresa il Tiramis\u00f9 batte spaghetti, Barilla, formaggio e maccheroni. La classifica del vino vede premiati Barolo (13%), Amarone (7%) e Chianti (6%), seguiti per\u00f2 da risposte come \u201cPiemonte\u201d, \u201cDocg\u201d, \u201cItalia\u201d, \u201cvino italiano\u201d, \u201cvino rosso\u201d e \u201cToscana\u201d, indicazioni che evidenziano una sostanziale confusione culturale rispetto al nostro prodotto enologico.<\/p>\n<p>Il risultato evidenziato rappresenta un estratto di una pi\u00f9 ampia indagine in corso di svolgimento relativa alla percezione del lifestyle italiano anche in rapporto ai propri competitor, ai gusti e alle abitudini di consumo dell\u2019upper class cinese di Pechino, Shanghai, Canton e Hong Kong per un campione complessivo di 2 mila intervistati.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pasta e il Barolo sarebbero il cibo e il vino italiani pi\u00f9 conosciuti dall\u2019upper class cinese. Ma a vincere \u00e8 la non conoscenza del made in Italy, con la met\u00e0 dei consumatori chiamati ad associare al Belpaese un prodotto\/brand agroalimentare che risponde \u2018non so\u2019. Lo rivela un estratto dell\u2019indagine dell\u2019Osservatorio Paesi terzi di Business [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":14758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[857,4281,1689,5613,591,1548,1475,1793,209,6276],"jetpack_featured_media_url":"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/08\/quadrifoglio-pasta1.jpg","_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/15664"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/comments?post=15664"}],"version-history":[{"count":2,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/15664\/revisions"}],"predecessor-version":[{"id":15666,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/15664\/revisions\/15666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media\/14758"}],"wp:attachment":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media?parent=15664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/categories?post=15664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags?post=15664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}