{"id":13853,"date":"2017-01-27T20:53:11","date_gmt":"2017-01-27T19:53:11","guid":{"rendered":"http:\/\/www.sceltedigusto.it\/public\/?p=13853"},"modified":"2017-01-27T20:53:11","modified_gmt":"2017-01-27T19:53:11","slug":"tutti-i-segreti-dellantica-cucina-siciliana-a-modica-il-debutto-de-i-quaderni-di-archestrato-calcentero","status":"publish","type":"post","link":"https:\/\/www.sceltedigusto.it\/public\/tutti-i-segreti-dellantica-cucina-siciliana-a-modica-il-debutto-de-i-quaderni-di-archestrato-calcentero\/","title":{"rendered":"Tutti i segreti dell\u2019antica cucina siciliana: a Modica il debutto de \u201cI Quaderni di Archestrato Calcentero\u201d"},"content":{"rendered":"<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato21.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-13857 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato21-300x199.jpg\" alt=\"archestrato2\" width=\"300\" height=\"199\" \/><\/a>Debutta nella propria citt\u00e0, culla di prodotti culinari d\u2019eccellenza, il sapiente volume sull\u2019archeogastronomia siciliana edito da Bonfirraro, gi\u00e0 salutato da lusinghieri consensi da parte di critica e lettori.<br \/>\nIl battesimo del libro \u201c<strong>I Quaderni di Archestrato Calcentero<\/strong> \u2013 <strong>divagazioni archeogastronomiche in terra di Sicilia<\/strong>\u201d si terr\u00e0, infatti, a Modica, citt\u00e0 nella quale \u00e8 nato, vive e lavora il suo giovane autore<strong> Marco Blanco<\/strong>, laureato in Lettere Classiche, libraio per professione e ricercatore per vocazione, che divide le sue giornate tra la passione per la lettura e la scrittura, la propria terra e l\u2019archeologia.<br \/>\n<a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato2.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-13856 alignright\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato2-193x300.jpg\" alt=\"archestrato\" width=\"193\" height=\"300\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato2-193x300.jpg 193w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato2-659x1024.jpg 659w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato2.jpg 1713w\" sizes=\"(max-width: 193px) 100vw, 193px\" \/><\/a>L\u2019appuntamento \u00e8 fissato per il prossimo 4 febbraio, a partire dalle ore 18.30, all\u2019auditorium \u201cP. Floridia\u201d. Durante l\u2019incontro interverranno l\u2019editore Salvo Bonfirraro, Pierpaolo Ruta dell\u2019Antica Dolceria Bonajuto \u2013 deus ex machina dell\u2019iniziativa letteraria insieme al compianto Franco Ruta \u2013 e Giancarlo Poidomani, docente di Storia Moderna presso la facolt\u00e0 di Scienze Politiche di Catania, autore della prefazione.<br \/>\nDialogher\u00e0 con l\u2019autore Carlo Ottaviano, giornalista enogastronomico di chiara fama, di origini ragusane, che ha curato un m\u00e9moire prestigioso, inserito in postfazione, nato dall\u2019incontro con Simonetta Agnello Hornby.<br \/>\nUn viaggio attraverso i sensi, tra una chicca letteraria e l\u2019altra, quello immaginato da Blanco e regalato al suo pubblico di lettori e buongustai, lungo il quale si dipanano e si sciolgono via via tutti i misteri di una bellissima e buonissima Sicilia culinaria a cavallo tra \u2018700 e \u2018800: dall\u2019arancinu, o meglio \u201cpiccole arance dorate\u201d, alla <strong>frutta delle monache \u201cMartorana\u201d di Palermo<\/strong>, la cui ricetta \u00e8 rimasta segreta per molto tempo.<br \/>\nAccanto alla maggiore fonte storica, che \u00e8 ovviamente quella del Pitr\u00e8, Blanco ha consultato e rielaborato decine di ricettari antichi, archivi di Stato, conventuali e privati diventati formidabili luoghi di scoperte.<a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato1.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-13855 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato1-251x300.jpg\" alt=\"archestrato1\" width=\"251\" height=\"300\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato1-251x300.jpg 251w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato1.jpg 320w\" sizes=\"(max-width: 251px) 100vw, 251px\" \/><\/a> \u00c8 cos\u00ec emerso che la particolare consistenza granulosa determinata dalla lavorazione a freddo del noto cioccolato di Modica era, infatti, una caratteristica comune a ogni cioccolato esistente al mondo almeno fino alla met\u00e0 dell\u2019Ottocento &#8211; ma adesso fiore all\u2019occhiello dell\u2019Antica Dolceria Bonajuto, grazie all\u2019intuizione di Franco e Pierpaolo Ruta \u2013 e che gli \u2018mpanatigghi, gli antichi dolcetti modicani con la carne macinata, erano anch\u2019essi custoditi gelosamente tra i muri dei conventi della citt\u00e0 iblea: non possono, dunque, mancare la succose narrazioni intorno agli ex Monastero di San Martino e al Convento di san Domenico, s\u00ec da scoprire che \u00abun elemento essenziale per la vita della comunit\u00e0 carmelitana di Modica era la neve\u00bb!<br \/>\n\u00ab<em>I prodotti enogastronomici sono il sale della nostra terra<\/em>\u00a0\u2013 afferma l\u2019editore Bonfirraro \u2013 <em>le pi\u00f9 grandi risorse su cui possiamo e dobbiamo investire, pensando a una nuova economia. Promuovere i prodotti locali e ricreare \u2018cultura\u2019 attorno ad essi non pu\u00f2 che essere la nostra mission, perseguita sin dagli esordi e il libro di Blanco si cala perfettamente in questo disegno di promozione del territorio, impregnato di una cultura infinita che rimanda alle istanze pi\u00f9 ancestrali dell\u2019uomo, ovvero il cibo\u00bb<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debutta nella propria citt\u00e0, culla di prodotti culinari d\u2019eccellenza, il sapiente volume sull\u2019archeogastronomia siciliana edito da Bonfirraro, gi\u00e0 salutato da lusinghieri consensi da parte di critica e lettori. Il battesimo del libro \u201cI Quaderni di Archestrato Calcentero \u2013 divagazioni archeogastronomiche in terra di Sicilia\u201d si terr\u00e0, infatti, a Modica, citt\u00e0 nella quale \u00e8 nato, vive [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":13857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[29],"tags":[],"jetpack_featured_media_url":"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2017\/01\/archestrato21.jpg","_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/13853"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/comments?post=13853"}],"version-history":[{"count":1,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/13853\/revisions"}],"predecessor-version":[{"id":13858,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/13853\/revisions\/13858"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media\/13857"}],"wp:attachment":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media?parent=13853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/categories?post=13853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags?post=13853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}