{"id":13407,"date":"2016-10-29T09:56:55","date_gmt":"2016-10-29T07:56:55","guid":{"rendered":"http:\/\/www.sceltedigusto.it\/public\/?p=13407"},"modified":"2016-10-29T09:56:55","modified_gmt":"2016-10-29T07:56:55","slug":"festivol-trevi-tra-olio-arte-musica-e-papille","status":"publish","type":"post","link":"https:\/\/www.sceltedigusto.it\/public\/festivol-trevi-tra-olio-arte-musica-e-papille\/","title":{"rendered":"\u201cFestivol&#8221;, Trevi tra olio, arte, musica e papille."},"content":{"rendered":"<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/pane-e-olio.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-13408 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/pane-e-olio-300x199.jpg\" alt=\"pane-e-olio\" width=\"300\" height=\"199\" \/><\/a>Inizia oggi, sabato 29 ottobre, \u201c<strong>Festivol<\/strong> \u2013 Trevi tra olio, arte, musica e papille\u201d, la kermesse che celebra ormai da 10 anni l\u2019olio nuovo, la prima spremitura e i Presidi Slow Food, primo tra tutti il Sedano Nero di Trevi; L\u2019evento coincide infatti con l\u2019apertura di Frantoi aperti.<\/p>\n<p>A dare il via all\u2019evento sar\u00e0 l\u2019inaugurazione della <strong>Mostra Mercato dell\u2019Olio Extravergine di Oliva<\/strong> delle colline di Trevi, in programma nella seicentesca Villa Fabri, sotto al loggiato del palazzo del Comune in piazza Mazzini invece la grande Mostra Mercato dei <strong>Presidi Slow Food dell\u2019Umbria<\/strong> (Sedano nero di Trevi, Fagiolina del Lago Trasimeno, Roveja di Civita di Cascia) e delle regioni ospiti: dalla Liguria,<strong> \u00a0Sedano nero di Trevi, Fagiolina del Lago Trasimeno, Roveja di Civita di Cascia, dal Lazio Il Caciofiore e la Marzolina di Capra, dal Friuli Venezia Giulia l\u2019Agio di Resia, la Cipolla Rossa, Il Pestat di Fagagna e il Radic di Mont, dalla Campania il Pomodorino Piennolo del Vesuvio Dop, dall\u2019Emilia Romagna la Mortadella Classica, dal Piemontela Piattella Canavesana di Cortereggio;<\/strong><br \/>\n<a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/frantoi.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-13409 alignright\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/frantoi-300x199.jpg\" alt=\"frantoi\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/frantoi-300x199.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/frantoi-100x65.jpg 100w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/frantoi.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Sempre nella Piazza del Comune il Mercato del Contadino, nella Piazza Garibaldi l\u2019ormai consolidato il Mercato delle Pulci; per gli appassionati di trekking, dalle ore 9.00, sar\u00e0 possibile partecipare all\u2019escursione lungo la Via di S. Francesco attraverso l\u2019acquedotto romano fino all\u2019antico olivo di s. Emiliano; per gli appassionati di natura, di cani e tartufo alle ore 9.30 da Villa Fabri si parte per una caccia al Tartufo, al termine la visita alla chiesa di San Pietro a Pettine e una degustazione a base di Tartufo e bruschetta con l\u2019olio appena franto. La particolarit\u00e0 di questo evento \u00e8 quello di scovare e aprire ai visitatori i palazzi storici privati della citt\u00e0 dove vengono organizzate degustazioni; Palazzi&amp;gusti sabato \u00e8 in programma dalle ore 15.30 alle ore 18.30 e sar\u00e0 visitabile per la prima volta il Collegietto Valenti di Piaggia dove poter assaggiare una <strong>Parmigiana di Sedano<\/strong> nero di Trevi a cura dell\u2019Agriturismo Villa Silvana in abbinamento al trebbiano spoletino Doc superiore Colle Uncinano Olio evo di Trevi e momenti musicali con Antonello De Lisi &#8211; chitarrista.<\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/Umbria.jpg\"><img loading=\"lazy\" class=\"wp-image-13410 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/Umbria.jpg\" alt=\"umbria\" width=\"263\" height=\"263\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/Umbria.jpg 204w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/Umbria-150x150.jpg 150w\" sizes=\"(max-width: 263px) 100vw, 263px\" \/><\/a>Un\u2019altra attivit\u00e0 dedicata alla cura di s\u00e9 \u00e8 Olio&amp;Benessere che si terr\u00e0 alle ore a Palazzo Petroni dalle ore 15.00 -18.30: saranno Massaggi viso e mani con cosmetici a base di olio di oliva.<\/p>\n<p>Segnaliamo inoltre un dibattico che si terr\u00e0 sempre domani alle ore 19.00 presso La Corte Fratini, in Via Cascia, Pigge, Trevi su \u201cIl Paesaggio della fascia olivata tra Assisi e Spoleto\u201d; a seguire una Cena di presentazione dell\u2019olio extravergine di oliva dei frantoi di Trevi a cura di \u201cIl Cavaliere\u201d<\/p>\n<p>Nei ristoranti di Trevi aderenti all\u2019evento (Taverna del Sette, Il Terziere, Locanda Cestellina, Il Poggio, Cantina del Bartoccio, Ristorante la Prepositura, e Agriturismo Villa Silvana), dalle ore 20.30 sar\u00e0 possibile assaggiare piatti realizzati con i presidi slow food Umbri e delle regioni ospiti.<\/p>\n<p>Attivo per tutta la giornata dalle 10 alle 18 da Piazza Garibaldi (vicino alle cabine telefoniche) un servizio navetta gratuita che collega il centro storico ai \u201cFrantoi Aperti\u201d di Trevi (Societ\u00e0 Agricola Trevi Il Frantoio, Frantoio del Gusto e Frantoio Gaudenzi).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inizia oggi, sabato 29 ottobre, \u201cFestivol \u2013 Trevi tra olio, arte, musica e papille\u201d, la kermesse che celebra ormai da 10 anni l\u2019olio nuovo, la prima spremitura e i Presidi Slow Food, primo tra tutti il Sedano Nero di Trevi; L\u2019evento coincide infatti con l\u2019apertura di Frantoi aperti. A dare il via all\u2019evento sar\u00e0 l\u2019inaugurazione [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":13408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,29],"tags":[8679,8677,8680,8678,8676],"jetpack_featured_media_url":"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/10\/pane-e-olio.jpg","_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/13407"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/comments?post=13407"}],"version-history":[{"count":1,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/13407\/revisions"}],"predecessor-version":[{"id":13411,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/13407\/revisions\/13411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media\/13408"}],"wp:attachment":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media?parent=13407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/categories?post=13407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags?post=13407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}