{"id":12839,"date":"2016-09-15T00:40:14","date_gmt":"2016-09-14T22:40:14","guid":{"rendered":"http:\/\/www.sceltedigusto.it\/public\/?p=12839"},"modified":"2016-09-16T08:43:33","modified_gmt":"2016-09-16T06:43:33","slug":"etichettatura-e-rintracciabilita-delle-carni-nella-filiera-alimentare","status":"publish","type":"post","link":"https:\/\/www.sceltedigusto.it\/public\/etichettatura-e-rintracciabilita-delle-carni-nella-filiera-alimentare\/","title":{"rendered":"Etichettatura e rintracciabilit\u00e0 delle carni nella filiera alimentare"},"content":{"rendered":"<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-12840 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne-300x300.jpg\" alt=\"scan-carne\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne-300x300.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne-150x150.jpg 150w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne-420x420.jpg 420w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne-210x210.jpg 210w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne.jpg 429w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La rintracciabilit\u00e0 \u00e8 uno strumento imposto dal legislatore comunitario in via generale per tutti gli alimenti con il Reg. CE 178\/2002 nell\u2019ottica di garantire: \u2013 sicurezza, intesa come capacit\u00e0 di gestire eventuali problematiche o emergenze sanitarie (si pensi in particolare alla funzionalit\u00e0 del sistema nell\u2019ottica di un recall del prodotto per non conformit\u00e0 igienico sanitaria); \u2013 fiducia nei consumatori; \u2013 controllo da parte delle autorit\u00e0 pubbliche. La \u201c&#8230; possibilit\u00e0 di ricostruire e seguire il percorso di un alimento, di un mangime, di un animale destinato alla produzione alimentare o di una sostanza destinata o atta ad entrare a far parte di un alimento o di un mangime attraverso tutte le fasi della produzione, della trasformazione e della distribuzione\u201c (Art. 3 comma 15 Reg. CE 178\/02) risulta strumentale al raggiungimento dei suddetti obiettivi. Per quel che concerne i prodotti di origine animale il sistema originariamente delineato dal Reg. 178\/2002 si \u00e8 rivelato insufficiente ed \u00e8 stata pertanto prevista, ad opera del Reg.to 931\/2011 applicabile dal 1\u00b0 luglio 2012, una rintracciabilit\u00e0 maggiormente dettagliata. Per alcuni prodotti alimentari come i prodotti della pesca, l\u2019olio extravergine di oliva, le uova, il legislatore comunitario ha individuato inoltre ulteriori specifiche normative verticali che prevedono anche determinate indicazioni obbligatorie di etichettatura dell\u2019alimento destinato al consumatore finale circa l\u2019origine del prodotto. Allo stato attuale, nel settore delle carni l\u2019origine \u00e8 indicazione obbligatoria per: \u2013 le carni bovine. Il Regolamento 1760\/2000 prevede l\u2019indicazione in etichetta del Paese di nascita, allevamento e macellazione dell\u2019animale. <a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/filiera.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-12841 alignright\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/filiera-300x190.jpg\" alt=\"filiera\" width=\"300\" height=\"190\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/filiera-300x190.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/filiera-745x475.jpg 745w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/filiera.jpg 750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Quando le carni provengono da un animale nato, detenuto e macellato in uno stesso Stato membro, queste informazioni possono essere raggruppate sotto un\u2019unica voce ORIGINE. Se alcune delle informazioni obbligatorie non sono disponibili per quanto riguarda prodotti importati \u00e8 sufficiente indicare \u201cORIGINE NON CE\u201d e il Paese di Macellazione. \u2013 Anche le carni bovine macinate devono riportare in etichetta la dicitura \u201cpreparato in\u201d (seguita dal nome dello Stato membro o del paese terzo). Tale informazione deve essere obbligatoriamente riportata anche dai titolari di punti vendita che preparano e mettono in vendita preincarti di carne macinata bovina. Deve inoltre figurare l\u2019indicazione dell\u2019origine nel caso in cui il paese o i paesi di nascita e di allevamento siano diversi da quello in cui \u00e8 avvenuta la preparazione del macinato e del paese di macellazione. \u2013 Per le sole carni di pollame importate da paesi terzi il Regolamento 543\/2008 prevede l\u2019indicazione obbligatoria del paese d\u2019origine. <a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/pollame.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-12842 alignleft\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/pollame-300x199.jpg\" alt=\"pollame\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/pollame-300x199.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/pollame-100x65.jpg 100w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/pollame.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Si ricorda in ogni caso che, con Ordinanza 26\/08\/2005, emanata sulla scorta dell\u2019emergenza \u201cinfluenza aviaria\u201d il legislatore nazionale ha previsto che, l\u2019operatore alimentare che effettua le operazioni di macellazione o sezionamento delle carni avicole deve indicare, mediante l\u2019apposizione su un\u2019apposita etichetta, sulla carcassa, o sul materiale di confezionamento o di imballaggio, la sigla IT oppure ITALIA seguita dal numero identificativo di registrazione presso la AUSL dell\u2019allevamento di provenienza degli animali. \u2013 Dal 13.12.2014 le carni suine, caprine e di volatili previa adozione da parte della Commissione europea degli atti di esecuzione basati su una valutazione di impatto che dovr\u00e0 prendere tra l\u2019altro in considerazione le opzioni sulle modalit\u00e0 di espressione del Paese d\u2019origine o del luogo di provenienza di detti alimenti, in particolare per quanto riguarda ciascuno dei seguenti momenti determinanti nella vita di un animale: \u2013 luogo di nascita; \u2013 luogo di allevamento; \u2013 luogo di macellazione. L\u2019allegato XI al regolamento 1169\/2011 precisa che l\u2019obbligo si applicher\u00e0 alle carni suine di cui al codice NC 0203 ovvero carni della specie suina fresche, refrigerate o congelate. Appartengono ad altra voce doganale e sono pertanto esclusi dall\u2019obbligo di indicazione dell\u2019origine, oltre alle altre preparazioni e conserve di carni, di frattaglie o di sangue di cui al codice nc 1602 le carni e frattaglie commestibili, salate o in salamoia, secche o affumicate. Per la restanti tipologie di carni (es carne di cavallo) la normativa generale sulla etichettatura o sulla rintracciabilit\u00e0 non obbliga gli diritto e legislazione potrebbero altrimenti far pensare che l\u2019alimento abbia un differente paese d\u2019origine o luogo di provenienza. Il legislatore italiano ha tentato gi\u00e0 dal 2004 di disciplinare in modo pi\u00f9 cogente tale indicazione ma i provvedimenti emanati in materia (l\u2019ultimo \u00e8 contenuto nell\u2019art. 4 della L. 4\/2011) sono rimasti \u201clettera morta\u201d non essendo mai stati emanati i relativi necessari provvedimenti attuativi. <a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/suini.jpeg\"><img loading=\"lazy\" class=\" wp-image-12843 alignright\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/suini-300x175.jpeg\" alt=\"suini\" width=\"379\" height=\"221\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/suini-300x175.jpeg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/suini-1024x597.jpeg 1024w\" sizes=\"(max-width: 379px) 100vw, 379px\" \/><\/a>Su piano comunitario il gi\u00e0 citato Regolamento 1169\/2011 prevede che \u201centro il 13.12.2014, la Commissione europea presenti al parlamento Europeo ed al Consiglio relazioni sull\u2019indicazione obbligatoria del paese di origine o del luogo di provenienza per determinati alimenti tra cui \u201ci tipi di carni diverse dalle carni bovine e da quelle di cui al paragrafo 2 lett. b)\u201d che sono le carni di animali della specie suina, ovina o caprina, fresche, refrigerate o congelate e di volatili. Pertanto \u00e8 prevedibile per il futuro una specifica disciplina dell\u2019indicazione dell\u2019origine per tutte tipologie di carni. Ci\u00f2 posto, si osserva che \u00e8 attualmente possibile indicare in via facoltativa in etichetta l\u2019origine, la provenienza o la filiera produttiva di un alimento. Tale comunicazione volontaria dovr\u00e0 osservare le regole della correttezza pubblicitaria o, nel caso in cui ci\u00f2 sia previsto, specifici disciplinari di etichettatura volontaria. A questo proposito viene in rilievo l\u2019art. 2 del d.lgs. 109\/92 che prevede che \u201cl\u2019etichettatura e le relative modalit\u00e0 di realizzazione sono destinate ad assicurare la corretta e trasparente informazione del consumatore. Esse devono essere effettuate in modo da: non indurre in errore l\u2019acquirente sulle caratteristiche del prodotto alimentare e precisamente sulla natura, sulla identit\u00e0, sulla qualit\u00e0, sulla composizione, sulla quantit\u00e0, sulla conservazione, sull\u2019origine o la provenienza, sul modo di fabbricazione o di ottenimento del prodotto [\u2026]\u201d. Per le tipologie di carne che non sono oggetto di normativa verticale di settore il problema dell\u2019origine risiede principalmente nella sua radicazione nelle ipotesi in cui nascita, ingrasso e macellazione dell\u2019animale avvengano in Paesi differenti.<\/p>\n<p><strong>Antonio Zagarese<\/strong><\/p>\n<p><strong>Studio Legale Avv. Carmine Coviello<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La rintracciabilit\u00e0 \u00e8 uno strumento imposto dal legislatore comunitario in via generale per tutti gli alimenti con il Reg. CE 178\/2002 nell\u2019ottica di garantire: \u2013 sicurezza, intesa come capacit\u00e0 di gestire eventuali problematiche o emergenze sanitarie (si pensi in particolare alla funzionalit\u00e0 del sistema nell\u2019ottica di un recall del prodotto per non conformit\u00e0 igienico sanitaria); [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":12840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6577],"tags":[],"jetpack_featured_media_url":"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/09\/scan-carne.jpg","_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/12839"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/comments?post=12839"}],"version-history":[{"count":1,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/12839\/revisions"}],"predecessor-version":[{"id":12844,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/12839\/revisions\/12844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media\/12840"}],"wp:attachment":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media?parent=12839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/categories?post=12839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags?post=12839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}