{"id":11999,"date":"2016-05-13T20:56:22","date_gmt":"2016-05-13T18:56:22","guid":{"rendered":"http:\/\/www.sceltedigusto.it\/public\/?p=11999"},"modified":"2016-05-17T13:05:35","modified_gmt":"2016-05-17T11:05:35","slug":"esperienze-gustose-conclusa-la-prima-edizione","status":"publish","type":"post","link":"https:\/\/www.sceltedigusto.it\/public\/esperienze-gustose-conclusa-la-prima-edizione\/","title":{"rendered":"Esperienze Gustose : conclusa la prima edizione"},"content":{"rendered":"<p><b>\u00a0<\/b><\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-12009 alignright\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831-300x194.jpg\" alt=\"identit\u00e0-golose-4-745x483\" width=\"300\" height=\"194\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831-300x194.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831-150x97.jpg 150w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831-696x451.jpg 696w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831-648x420.jpg 648w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831-100x65.jpg 100w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4-745x4831.jpg 745w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Si \u00e8 svolta dal 6 all\u20198 maggio la prima edizione di <strong>Esperienze Gustose<\/strong>, evento-tributo dedicato al food e ai suoi protagonisti, ideato dall\u2019agenzia Tempo di Eventi di Paola Castellani. Tre giorni di <strong>cooking session, laboratori di degustazione e assaggi<\/strong>, ospitati nei saloni quattrocenteschi di <strong>Villa La Mattarana<\/strong> a Verona.\u00a0<a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-gustose-fb-.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-12001 size-full\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-gustose-fb-.jpg\" alt=\"esperienze-gustose-(-fb-)-\" width=\"180\" height=\"180\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-gustose-fb-.jpg 180w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-gustose-fb--150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-1.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-11991 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-1-300x200.jpg\" alt=\"Saverio Crea Onlus\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-1-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-1-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-1.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>All\u2019evento hanno preso parte professionisti della ristorazione, foodie, appassionati gourmet, giornalisti e foodblogger, provenienti da tutta Italia. Tra i protagonisti, grandi nomi dell\u2019eccellenza italiana, come <strong>Ernst Knam<\/strong>, <strong>chef Hiro, Italo Bassi, Renato Bosco, Andrea Mainardi, Eugenio Boer<\/strong> e molti altri ancora.<\/p>\n<p>Il programma completo e tutti i dettagli su <strong>www.esperienzegustose.it<\/strong>, di seguito il report dei momenti salienti delle tre giornate di lavori.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Venerd\u00ec 6 maggio<\/strong><\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-2.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-11992 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-2-200x300.jpg\" alt=\"Saverio Crea Onlus\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-2-200x300.jpg 200w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-2-682x1024.jpg 682w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-2.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>L\u2019apertura dei lavori \u00e8 stata affidata alla tavola rotonda <strong>\u201cSinergia tra cucina e sala: come la ristorazione diventa eccellenza\u201d<\/strong>. Il giornalista <strong>Carlo Passera<\/strong> di <em>Identit\u00e0 Golose<\/em> ha presentato il libro \u201c<em>100 chef x 10 anni<\/em>\u201d di cui \u00e8 co-autore, edito da Mondadori. Carlo Passera stesso ha poi moderato il dibattito, al quale sono intervenuti chef <strong>Italo Bassi<\/strong>, il ma\u00eetre <strong>Damian Piotr Janczara<\/strong> di Essenza Ristorante, <strong>Walter Meccia <\/strong>sommelier del ristorante stellato Il Palagio di Firenze e delegato di <strong>Noi Di Sala<\/strong> e infine la sommelier <strong>Nadia Salvador<\/strong> di <strong>Fisar<\/strong>. L\u2019argomento si \u00e8 dimostrato fin dai primi scambi di battute estremamente attuale e sentito: la sala e il servizio stanno assumendo un\u2019importanza sempre pi\u00f9 di rilievo nel panorama della ristorazione di qualit\u00e0. Come sottolineato da chef Italo Bassi &#8211; che dopo la sua decennale esperienza nel ristorante Enoteca Pinchiorri di Firenze (3 stelle Michelin) \u00e8 oggi titolare del locale ConFusion a Verona e pronto ad una nuova apertura a Porto Cervo \u2013 di fondamentale importanza \u00e8 la <strong>formazione negli istituti alberghieri<\/strong>, oltre che l\u2019introduzione di <strong>agevolazioni per le assunzioni<\/strong> rivolte agli imprenditori nella ristorazione. In questo modo, in ogni tipo di ristorante \u2013 non solo negli stellati -, si potrebbe investire la giusta energia nella formazione dei camerieri e di tutto il personale a contatto con il cliente.<a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-3.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-11993 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-3-300x200.jpg\" alt=\"Saverio Crea Onlus\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-3-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-3-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-3.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La serata di venerd\u00ec 6 maggio \u00e8 stata dedicata alla <strong>Mixology Experience<\/strong>, durante la quale Leonardo Pinto di Isla de Rum ha presentato i cocktail, preparati dal bartender Mirco Guizzardi, in abbinamento ai piatti di chef Gabriele Sechi, il quale ha interpretato con creativit\u00e0 un ingrediente eccezionale, ovvero il <strong>Caviale Calvisius<\/strong>. La miscelazione a servizio della cucina: un\u2019abbinata decisamente apprezzata dal pubblico in sala.<br \/>\nNelle sala affrescata dedicata ai laboratori di degustazione, ha riscosso grande successo l\u2019intervento del sommelier <strong>Andrea Da Ros<\/strong> di Fisar, che ha tenuto una lezione-degustazione sui Sauvignon Blanc, attraverso ben cinque assaggi provenienti da Francia, Italia e Nuova Zelanda.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sabato 7 maggio<\/strong><\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-5.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-11995 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-5-200x300.jpg\" alt=\"identit\u00e0-golose-5\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-5-200x300.jpg 200w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-5-682x1024.jpg 682w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-5.jpg 1200w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>Intensa e ricchissima di appuntamenti la seconda giornata di Esperienze Gustose: sul palco della sala convegni si sono susseguiti 6 chef, i quali hanno rapito il pubblico con le loro preparazioni, incalzati e intervistati da Paola Castellani.<\/p>\n<p><strong>Alberto Basso<\/strong> del ristorante 3Quarti di Grancona (Vicenza) ha deliziato la platea con uno dei suoi piatti-simbolo: <em>Risi e latte con miele, sfera di birra al lampone e ribes. <\/em>La sua giovane et\u00e0, unita ad una professionalit\u00e0 elegante e composta che gli \u00e8 valsa l\u2019ingresso pochi mesi fa nell\u2019associazione JRE (Jeunes Restaurateurs d\u2019Europe), ha affascinato tutti.<\/p>\n<p>Travolgente e esuberante la chef a domicilio <strong>Francesca Marsetti<\/strong>, volto tv de <em>La Prova del Cuoco, <\/em>che ha presentato insieme all\u2019ideatrice Chiara Rota la start up My Cooking Box, per poi passare alla preparazione della sua personale visione di comfort food: <em>Triglie di scoglio su passatina di mais con cipollotti caramellati e noci.<a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-11.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-12003 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-11-300x200.jpg\" alt=\"Saverio Crea Onlus\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-11-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-11-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-11.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/em><\/p>\n<p>Ha portato la firma di chef <strong>Davide Botta <\/strong>dell\u2019Artigliere di Isola della Scala (Verona) un omaggio al riso di rara eccellenza: la sua cooking session \u00e8 stata interamente dedicata al <em>Vialone Nano: riso latte, melone pressato, gambero rosso, asparagi verdi e sugo ristretto di carne al porto<\/em>.<\/p>\n<p>Folla in sala per chef <strong>Ernst Knam<\/strong>, il quale ha tenuto una lectio magistralis di pasticceria durata quasi due ore: accompagnato dalle domande discrete e sempre puntuali di Vatin\u00e9e Suvimol, volto di iFood (media partner dell\u2019evento), il pasticcere ha preparato 3 grandi classici, nelle loro versioni tradizionali e rivisitate. Sei dessert che hanno estasiato tutti i partecipanti.<\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-6.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-11996 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-6-300x200.jpg\" alt=\"identit\u00e0-golose-6\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-6-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-6-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-6.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>L\u2019accento esilarante e la personalit\u00e0 scoppiettante di <strong>chef Hiro<\/strong> sono stati i protagonisti di una cooking session dedicata all\u2019esaltazione della materia prima nella sua essenzialit\u00e0, poi espressa nel piatto <em>Capesante scottate con salsa mandorle, caviale di olive, insalata aromatica e schiuma di rapa rossa.<\/em><\/p>\n<p>Ha chiuso la giornata l\u2019intervento di <strong>Renato Bosco<\/strong>, che dapprima ha dedicato la sua cooking session all\u2019evocativo piatto <em>Pane, latte e&#8230; Il latte? Una ratatouille di associazioni ed emozioni<\/em> e poi si \u00e8 raccontato al microfono di Roberta Morasco di iFood. In seguito, ha servito il suo famoso Doppio Crunch preparato con lievito madre e declinato in tre goduriose versioni: vegetariano, vegano e con Speck abbinato al Monte Veronese. Ad accompagnare la degustazione, i prodotti di quattro birrifici artigianali: <strong>Birra Lessinia, Il Birrificio Inesistente, Birrificio Ofelia e Birrificio Benaco<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Domenica 8 maggio<\/strong><\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-7.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-11997 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-7-300x200.jpg\" alt=\"identit\u00e0-golose-7\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-7-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-7-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-7.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>L\u2019ultima giornata \u00e8 iniziata in dolcezza con la cooking session della pasticcera <strong>Giada Farina<\/strong> de le Torte di Giada (Brescia), che ha preparato per il pubblico il suo <em>Pancake bread con crema della nonna<\/em>. Ad introdurre il suo intervento c\u2019era <strong>Monica Zacchia<\/strong> di iFood, che proprio a Esperienze Gustose ha presentato in anteprima nazionale il suo libro <em>Le Fluffose<\/em>, dedicato alla chiffon cake e alle sue deliziose versioni.<\/p>\n<p>Volto di My Cooking Box, chef <strong>Fabio Potenzano<\/strong> ha reso omaggio alla sua terra, la Sicilia, dapprima preparando le <em>Busiate di grano duro biologico Tumminia, con pomodoro ciliegino, capperi lilliput e olive, <\/em>per poi destreggiarsi in un magnifico<em> Sicily Burger: burger di pesce azzurro panato con fiocchi di legumi, verdure in agrodolce e maionese alla mandorla<\/em>.\u00a0<a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-8.jpg\"><img loading=\"lazy\" class=\"alignright wp-image-11998 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-8-300x200.jpg\" alt=\"Saverio Crea Onlus\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-8-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-8-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-8.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-9.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-12004 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-9-300x200.jpg\" alt=\"Saverio Crea Onlus\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-9-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-9-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-9.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Il climax della giornata \u00e8 stato certamente la sfida ai fornelli delle finaliste del concorso FoodBloggest, condotta dallo chef <strong>Andrea Mainardi<\/strong>, a dir poco esplosivo, il quale ha intrattenuto concorrenti e partecipanti con un carisma degno di un one-man-show. La giuria, composta dalla giornalista Camilla Rocca, dalla pasticcera Giada Farina, dallo chef Fabio Potenzano e dalla ex concorrente di MasterChef 5 Lucia Giorgi, ha decretato la vincitrice: Francesca Bettoni del blog beautyfoodblog.it, che ha conquistato anche il pubblico con la sua <em>Pastiera vegana senza glutine<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel pomeriggio, \u00e8 salito sul palco chef <strong>Andrea Valentinetti<\/strong> di d&amp;g patisserie di Selvazzano Dentro (Padova), che ha proposto la sua versione classica del piatto <em>Risi e bisi<\/em>, poi declinato in una versione contemporanea e estremamente originale.<\/p>\n<p>La chiusura degli show cooking \u00e8 stata affidata a chef <strong>Eugenio<\/strong> <strong>Boer <\/strong>di Essenza Ristorante a Milano, che ha letteralmente stregato tutti con la sua preparazione, ma anche con i suoi contenuti di spessore. Ha preparato per il pubblico il divino <em>Risotto lavanda, capra, polline e ortiche.<\/em><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p><a href=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-10.jpg\"><img loading=\"lazy\" class=\"alignleft wp-image-12005 size-medium\" src=\"http:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-10-300x200.jpg\" alt=\"Saverio Crea Onlus\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-10-300x200.jpg 300w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-10-1024x682.jpg 1024w, https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/esperienze-golose-10.jpg 1800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Per tutta la giornata, nelle sale-laboratorio \u00e8 stato un susseguirsi di mini-corsi di degustazione e assaggi gratuiti, tutti dedicati a prodotti dell\u2019eccellenza nazionale e internazionale. Anche i pi\u00f9 piccoli sono stati impegnati in laboratori dedicati a loro, organizzati da BimbiChef, \u00c8Cucina e le Torte di Giada.<\/p>\n<p><strong>Conclusioni<\/strong><br \/>\nTre giorni intensi, ricchi di iniziative e appuntamenti, resi possibili grazie all\u2019iniziativa e alla creativit\u00e0 dell\u2019ideatrice Paola Castellani e il team dell\u2019agenzia Tempo di Eventi. Grazie anche alla collaborazione e al sostegno dei numerosi partner e sponsor, la prima edizione ha saputo regalare grandi soddisfazioni, tanto che gi\u00e0 si pensa alla seconda edizione, che si svolger\u00e0 nel 2017.<\/p>\n<p>Per interviste e approfondimenti: info@esperienzegustose.it<\/p>\n<p><span class=\"Apple-style-span\">credits: Roberto Ricca\/Roberto Massini<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Si \u00e8 svolta dal 6 all\u20198 maggio la prima edizione di Esperienze Gustose, evento-tributo dedicato al food e ai suoi protagonisti, ideato dall\u2019agenzia Tempo di Eventi di Paola Castellani. Tre giorni di cooking session, laboratori di degustazione e assaggi, ospitati nei saloni quattrocenteschi di Villa La Mattarana a Verona.\u00a0 All\u2019evento hanno preso parte professionisti [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":11994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,29,5435],"tags":[8179,8178,8152,8177,8172,8173,8181,8149,8147,5914,5891,8180,8150,8176,8175,8151,8148,8174],"jetpack_featured_media_url":"https:\/\/www.sceltedigusto.it\/public\/wp-content\/uploads\/2016\/05\/identit\u00e0-golose-4.jpg","_links":{"self":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/11999"}],"collection":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/comments?post=11999"}],"version-history":[{"count":5,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/11999\/revisions"}],"predecessor-version":[{"id":12010,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/posts\/11999\/revisions\/12010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media\/11994"}],"wp:attachment":[{"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/media?parent=11999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/categories?post=11999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sceltedigusto.it\/public\/wp-json\/wp\/v2\/tags?post=11999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}